{"id":162,"count":1,"description":"","link":"https:\/\/chloelina.com\/authentic\/tag\/basil\/","name":"basil","slug":"basil","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>basil Archives | The Authentic Life<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chloelina.com\/authentic\/tag\/basil\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"basil Archives | The Authentic Life\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chloelina.com\/authentic\/tag\/basil\/\" \/>\n<meta property=\"og:site_name\" content=\"The Authentic Life\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/tag\\\/basil\\\/\",\"url\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/tag\\\/basil\\\/\",\"name\":\"basil Archives | The Authentic Life\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/tag\\\/basil\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/tag\\\/basil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"basil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/#website\",\"url\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/\",\"name\":\"The Authentic Life\",\"description\":\"Live Life with Intention\",\"publisher\":{\"@id\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/#organization\",\"name\":\"The Chloelina All Natural Soap Co\",\"url\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/LOGO-website-medium-graphic.png\",\"contentUrl\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/LOGO-website-medium-graphic.png\",\"width\":500,\"height\":313,\"caption\":\"The Chloelina All Natural Soap Co\"},\"image\":{\"@id\":\"https:\\\/\\\/chloelina.com\\\/authentic\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/instagram.com\\\/_theauthenticlife_\",\"https:\\\/\\\/www.pinterest.com\\\/chloelina\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"basil Archives | The Authentic Life","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chloelina.com\/authentic\/tag\/basil\/","og_locale":"en_US","og_type":"article","og_title":"basil Archives | The Authentic Life","og_url":"https:\/\/chloelina.com\/authentic\/tag\/basil\/","og_site_name":"The Authentic Life","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/chloelina.com\/authentic\/tag\/basil\/","url":"https:\/\/chloelina.com\/authentic\/tag\/basil\/","name":"basil Archives | The Authentic Life","isPartOf":{"@id":"https:\/\/chloelina.com\/authentic\/#website"},"breadcrumb":{"@id":"https:\/\/chloelina.com\/authentic\/tag\/basil\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/chloelina.com\/authentic\/tag\/basil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chloelina.com\/authentic\/"},{"@type":"ListItem","position":2,"name":"basil"}]},{"@type":"WebSite","@id":"https:\/\/chloelina.com\/authentic\/#website","url":"https:\/\/chloelina.com\/authentic\/","name":"The Authentic Life","description":"Live Life with Intention","publisher":{"@id":"https:\/\/chloelina.com\/authentic\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chloelina.com\/authentic\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/chloelina.com\/authentic\/#organization","name":"The Chloelina All Natural Soap Co","url":"https:\/\/chloelina.com\/authentic\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chloelina.com\/authentic\/#\/schema\/logo\/image\/","url":"https:\/\/chloelina.com\/authentic\/wp-content\/uploads\/2022\/01\/LOGO-website-medium-graphic.png","contentUrl":"https:\/\/chloelina.com\/authentic\/wp-content\/uploads\/2022\/01\/LOGO-website-medium-graphic.png","width":500,"height":313,"caption":"The Chloelina All Natural Soap Co"},"image":{"@id":"https:\/\/chloelina.com\/authentic\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/instagram.com\/_theauthenticlife_","https:\/\/www.pinterest.com\/chloelina"]}]}},"_links":{"self":[{"href":"https:\/\/chloelina.com\/authentic\/wp-json\/wp\/v2\/tags\/162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chloelina.com\/authentic\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/chloelina.com\/authentic\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/chloelina.com\/authentic\/wp-json\/wp\/v2\/posts?tags=162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}